{"id":3909,"date":"2022-01-26T12:41:00","date_gmt":"2022-01-26T11:41:00","guid":{"rendered":"https:\/\/fr.koddos.net\/blog\/?p=3909"},"modified":"2022-01-27T12:45:49","modified_gmt":"2022-01-27T11:45:49","slug":"les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs","status":"publish","type":"post","link":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/","title":{"rendered":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS"},"content":{"rendered":"\n<p>Un rapport r\u00e9cent a r\u00e9v\u00e9l\u00e9 que les acteurs de menaces d\u00e9tournent les comptes Instagram des influenceurs et des entreprises pour escroquer les victimes dans une nouvelle <strong><a href=\"https:\/\/blog.koddos.net\/google-discovers-new-malware-campaign-that-exploits-zero-days\/\">campagne de phishing<\/a><\/strong>.<\/p>\n\n\n\n<p>Selon le rapport, la campagne a \u00e9t\u00e9 d\u00e9couverte en octobre de l&rsquo;ann\u00e9e derni\u00e8re. Les hackers prennent le contr\u00f4le des comptes de ces influenceurs et demandent une ran\u00e7on pour lib\u00e9rer les comptes \u00e0 leurs propri\u00e9taires l\u00e9gitimes.<\/p>\n\n\n\n<p>Les mauvais acteurs responsables de l&rsquo;attaque commencent par envoyer un message et le d\u00e9guiser en Instagram pour informer les utilisateurs sur des cas de confidentialit\u00e9. Le message contient un lien qui envoie les victimes vers un site web g\u00e9r\u00e9 par des hackers. Une fois que l&rsquo;utilisateur se rend sur la page et saisit les d\u00e9tails de son compte Instagram, l&rsquo;acteur malveillant obtient un acc\u00e8s complet aux comptes et bloque l&rsquo;utilisateur en modifiant les informations.<\/p>\n\n\n\n<p><strong>Les hackers envoient un message de ran\u00e7on apr\u00e8s avoir pirat\u00e9 les comptes<\/strong><\/p>\n\n\n\n<p>Selon Secureworks, une fois que l&rsquo;attaquant a r\u00e9ussi \u00e0 changer le nom d&rsquo;utilisateur, il commence \u00e0 envoyer des messages de ran\u00e7on \u00e0 la victime, lui demandant de payer ou de risquer de perdre ses comptes. La plupart des comptes vis\u00e9s sont des comptes Instagram populaires avec beaucoup de followers.<\/p>\n\n\n\n<p>Les hackers s&rsquo;attaquent \u00e9galement aux comptes d&rsquo;entreprises qui ne souhaitent pas perdre le contact de leurs clients sur les m\u00e9dias sociaux.<\/p>\n\n\n\n<p>Le nom d&rsquo;utilisateur mis \u00e0 jour utilise une variante de \u00ab\u00a0pharabenphaway\u00a0\u00bb et le nombre de followers du compte pirat\u00e9.<\/p>\n\n\n\n<p>Une fois le compte pirat\u00e9 avec succ\u00e8s, l&rsquo;attaquant ajoute le commentaire suivant au profil : \u00ab\u00a0Ce compte Instagram est conserv\u00e9 pour la vente au propri\u00e9taire\u00a0\u00bb. L&rsquo;acteur de la menace envoie \u00e9galement un autre message qui informe la victime d&rsquo;entamer des n\u00e9gociations de ran\u00e7on avec lui ou de risquer de perdre compl\u00e8tement son compte.<\/p>\n\n\n\n<p>Un lien est \u00e9galement attach\u00e9 au profil. Il comprend le nom de domaine WhatsApp raccourci (wa.me) ainsi que le num\u00e9ro de contact.<\/p>\n\n\n\n<p>Lorsque la victime clique sur le lien, elle est redirig\u00e9e vers une conversation WhatsApp o\u00f9 elle peut n\u00e9gocier les termes de la ran\u00e7on avec les <strong><a href=\"https:\/\/blog.koddos.net\/hackers-threaten-to-delete-stolen-data-by-demanding-ransom-in-cryptocurrencies\/\">hackers<\/a><\/strong>.<\/p>\n\n\n\n<p><strong>Les hackers sont bas\u00e9s en Turquie et en Russie<\/strong><\/p>\n\n\n\n<p>Secureworks a d\u00e9clar\u00e9 que les acteurs de la menace avaient d\u00e9j\u00e0 pirat\u00e9 plusieurs comptes lorsqu&rsquo;ils ont lanc\u00e9 la campagne l&rsquo;ann\u00e9e derni\u00e8re.<\/p>\n\n\n\n<p>Si la victime refuse de n\u00e9gocier avec le hacker ou ne r\u00e9pond pas \u00e0 la <strong><a href=\"https:\/\/blog.koddos.net\/russian-authorities-arrest-members-of-the-infamous-revil-ransomware-gang\/\">demande de ran\u00e7on<\/a><\/strong>, les hackers sont contraints de vendre le compte sur le darknet (un forum en ligne clandestin pour les hackers et autres mauvais acteurs).<\/p>\n\n\n\n<p>En effectuant des recherches sur le forum clandestin, les chercheurs en s\u00e9curit\u00e9 ont d\u00e9couvert en septembre un message qui vend l&rsquo;acc\u00e8s \u00e0 un compte Instagram saisi pour 40 000 dollars.<\/p>\n\n\n\n<p>Secureworks a \u00e9galement not\u00e9 que les acteurs de la menace fournissent g\u00e9n\u00e9ralement des num\u00e9ros de t\u00e9l\u00e9phone, ce qui indique qu&rsquo;ils op\u00e8rent depuis la Turquie et la Russie. Une autre preuve montre qu&rsquo;ils sont bas\u00e9s en Russie.<\/p>\n\n\n\n<p><strong>Les acteurs de la menace peuvent avoir acc\u00e8s aux documents vitaux des entreprises<\/strong><\/p>\n\n\n\n<p>Dans l&rsquo;une des communications avec une victime, le hacker a utilis\u00e9 la version turque d&rsquo;Instagram. De plus, l&rsquo;une des sources de la page du site de phishing fait r\u00e9f\u00e9rence au service de partage de fichiers turc hizliresim .com.<\/p>\n\n\n\n<p>Les chercheurs ont ajout\u00e9 que ce type d&rsquo;attaque peut donner aux acteurs de la menace un acc\u00e8s non autoris\u00e9 aux comptes de messagerie et \u00e0 d&rsquo;autres ressources importantes de l&rsquo;entreprise si les mots de passe sont r\u00e9utilis\u00e9s. Dans la plupart des attaques de phishing, l&rsquo;attaquant tente d&rsquo;obtenir des informations vitales sur le compte de l&rsquo;utilisateur.<\/p>\n\n\n\n<p>Le d\u00e9tournement de comptes Instagram sugg\u00e8re que les acteurs de la menace sont principalement int\u00e9ress\u00e9s par la <strong><a href=\"https:\/\/blog.koddos.net\/hackers-offer-over-85000-sql-databases-on-the-dark-net\/\">collecte de ran\u00e7ons<\/a><\/strong> aupr\u00e8s de leurs victimes.<\/p>\n\n\n\n<p>Mais dans certains cas, les hackers pourraient mettre la main sur des courriels d&rsquo;entreprise importants et des ressources qu&rsquo;ils pourraient utiliser pour d&rsquo;autres formes d&rsquo;attaques \u00e0 l&rsquo;avenir.<\/p>\n\n\n\n<p>On ne sait pas exactement combien de personnes ou d&rsquo;organisations ont \u00e9t\u00e9 victimes de ce type d&rsquo;attaque. Mais comme la campagne a commenc\u00e9 en septembre de l&rsquo;ann\u00e9e derni\u00e8re, certaines personnes ont peut-\u00eatre d\u00e9j\u00e0 \u00e9t\u00e9 victimes.<\/p>\n\n\n\n<p><strong>Le nombre de hackers en augmentation sur les m\u00e9dias sociaux<\/strong><\/p>\n\n\n\n<p>Cette derni\u00e8re campagne prouve que les acteurs de menaces ne rel\u00e2chent pas leurs efforts pour obtenir des gains financiers, que ce soit par la vuln\u00e9rabilit\u00e9 des r\u00e9seaux ou par des <strong><a href=\"https:\/\/blog.koddos.net\/scammers-are-using-sophisticated-phishing-methods-to-get-bank-customers-details\/\">m\u00e9thodes de phishing<\/a><\/strong>. C&rsquo;est aussi une indication que les m\u00e9dias sociaux deviennent de plus en plus le festin des hackers, qui utilisent divers moyens pour obtenir des fonds de leurs victimes, notamment le chantage et les demandes de ran\u00e7on.<\/p>\n\n\n\n<p>Par cons\u00e9quent, il a \u00e9t\u00e9 conseill\u00e9 aux gens de redoubler d&rsquo;efforts pour se prot\u00e9ger en ligne. La r\u00e9cente attaque attire une fois de plus l&rsquo;attention des entreprises qui utilisent les m\u00e9dias sociaux pour gagner des clients et d\u00e9velopper leurs marques. Elle a \u00e9galement mis en \u00e9vidence l&rsquo;importance croissante des influenceurs sur les m\u00e9dias sociaux et la n\u00e9cessit\u00e9 pour eux de mieux se prot\u00e9ger.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un rapport r\u00e9cent a r\u00e9v\u00e9l\u00e9 que les acteurs de menaces d\u00e9tournent les comptes Instagram des influenceurs et des entreprises pour escroquer les victimes dans une nouvelle campagne de phishing. Selon le rapport, la campagne a \u00e9t\u00e9 d\u00e9couverte en octobre de l&rsquo;ann\u00e9e derni\u00e8re. Les hackers prennent le contr\u00f4le des comptes de ces influenceurs et demandent une &hellip; <a href=\"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":1320,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-3909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS\" \/>\n<meta property=\"og:description\" content=\"Un rapport r\u00e9cent a r\u00e9v\u00e9l\u00e9 que les acteurs de menaces d\u00e9tournent les comptes Instagram des influenceurs et des entreprises pour escroquer les victimes dans une nouvelle campagne de phishing. Selon le rapport, la campagne a \u00e9t\u00e9 d\u00e9couverte en octobre de l&rsquo;ann\u00e9e derni\u00e8re. Les hackers prennent le contr\u00f4le des comptes de ces influenceurs et demandent une &hellip; Continue reading LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog KoDDoS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/koddosCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-26T11:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-27T11:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"825\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"KoDDoS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@koddoscom\" \/>\n<meta name=\"twitter:site\" content=\"@koddoscom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"KoDDoS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/\"},\"author\":{\"name\":\"KoDDoS\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/person\\\/d22f7fb31dc4d117c9eb5c9cfe533f85\"},\"headline\":\"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS\",\"datePublished\":\"2022-01-26T11:41:00+00:00\",\"dateModified\":\"2022-01-27T11:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/\"},\"wordCount\":933,\"publisher\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/\",\"name\":\"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1\",\"datePublished\":\"2022-01-26T11:41:00+00:00\",\"dateModified\":\"2022-01-27T11:45:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1\",\"width\":825,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\",\"name\":\"Blog KoDDoS\",\"description\":\"Blog KoDDoS est un blog d\u2019information et d\u2019actualit\u00e9 focalis\u00e9 sur le hacking, la cyber criminalit\u00e9, la vie priv\u00e9e et la surveillance.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\",\"name\":\"KoDDoS\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo.png?fit=258%2C55&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo.png?fit=258%2C55&ssl=1\",\"width\":258,\"height\":55,\"caption\":\"KoDDoS\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/koddosCom\",\"https:\\\/\\\/x.com\\\/koddoscom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/person\\\/d22f7fb31dc4d117c9eb5c9cfe533f85\",\"name\":\"KoDDoS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"caption\":\"KoDDoS\"},\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/author\\\/oiyndjepop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/","og_locale":"fr_FR","og_type":"article","og_title":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS","og_description":"Un rapport r\u00e9cent a r\u00e9v\u00e9l\u00e9 que les acteurs de menaces d\u00e9tournent les comptes Instagram des influenceurs et des entreprises pour escroquer les victimes dans une nouvelle campagne de phishing. Selon le rapport, la campagne a \u00e9t\u00e9 d\u00e9couverte en octobre de l&rsquo;ann\u00e9e derni\u00e8re. Les hackers prennent le contr\u00f4le des comptes de ces influenceurs et demandent une &hellip; Continue reading LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS","og_url":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/","og_site_name":"Blog KoDDoS","article_publisher":"https:\/\/www.facebook.com\/koddosCom","article_published_time":"2022-01-26T11:41:00+00:00","article_modified_time":"2022-01-27T11:45:49+00:00","og_image":[{"width":825,"height":510,"url":"https:\/\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg","type":"image\/jpeg"}],"author":"KoDDoS","twitter_card":"summary_large_image","twitter_creator":"@koddoscom","twitter_site":"@koddoscom","twitter_misc":{"\u00c9crit par":"KoDDoS","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#article","isPartOf":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/"},"author":{"name":"KoDDoS","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/person\/d22f7fb31dc4d117c9eb5c9cfe533f85"},"headline":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS","datePublished":"2022-01-26T11:41:00+00:00","dateModified":"2022-01-27T11:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/"},"wordCount":933,"publisher":{"@id":"https:\/\/fr.koddos.net\/blog\/#organization"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/","url":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/","name":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS - Blog KoDDoS","isPartOf":{"@id":"https:\/\/fr.koddos.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#primaryimage"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1","datePublished":"2022-01-26T11:41:00+00:00","dateModified":"2022-01-27T11:45:49+00:00","breadcrumb":{"@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#primaryimage","url":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1","width":825,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/fr.koddos.net\/blog\/les-hackers-ciblent-les-entreprises-et-les-influenceurs-sur-instagram-avertissent-les-chercheurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.koddos.net\/blog\/"},{"@type":"ListItem","position":2,"name":"LES HACKERS CIBLENT LES ENTREPRISES ET LES INFLUENCEURS SUR INSTAGRAM, AVERTISSENT LES CHERCHEURS"}]},{"@type":"WebSite","@id":"https:\/\/fr.koddos.net\/blog\/#website","url":"https:\/\/fr.koddos.net\/blog\/","name":"Blog KoDDoS","description":"Blog KoDDoS est un blog d\u2019information et d\u2019actualit\u00e9 focalis\u00e9 sur le hacking, la cyber criminalit\u00e9, la vie priv\u00e9e et la surveillance.","publisher":{"@id":"https:\/\/fr.koddos.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.koddos.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fr.koddos.net\/blog\/#organization","name":"KoDDoS","url":"https:\/\/fr.koddos.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2018\/02\/logo.png?fit=258%2C55&ssl=1","contentUrl":"https:\/\/i1.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2018\/02\/logo.png?fit=258%2C55&ssl=1","width":258,"height":55,"caption":"KoDDoS"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/koddosCom","https:\/\/x.com\/koddoscom"]},{"@type":"Person","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/person\/d22f7fb31dc4d117c9eb5c9cfe533f85","name":"KoDDoS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","caption":"KoDDoS"},"url":"https:\/\/fr.koddos.net\/blog\/author\/oiyndjepop\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9DjzA-113","jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2019\/10\/White-Hat-Hacker-Takes-Back-Millions-of-Credit-Cards-Stolen-by-Cybercriminals.jpg?fit=825%2C510&ssl=1","_links":{"self":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/comments?post=3909"}],"version-history":[{"count":1,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3909\/revisions"}],"predecessor-version":[{"id":3910,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3909\/revisions\/3910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/media\/1320"}],"wp:attachment":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/media?parent=3909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/categories?post=3909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/tags?post=3909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}