{"id":3956,"date":"2022-02-16T09:19:00","date_gmt":"2022-02-16T08:19:00","guid":{"rendered":"https:\/\/fr.koddos.net\/blog\/?p=3956"},"modified":"2022-02-16T19:25:51","modified_gmt":"2022-02-16T18:25:51","slug":"une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server","status":"publish","type":"post","link":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/","title":{"rendered":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER"},"content":{"rendered":"\n<p>Une s\u00e9rie d&rsquo;attaques de cybers\u00e9curit\u00e9 a \u00e9t\u00e9 d\u00e9tect\u00e9e sur Microsoft Exchange Server. Les attaques ont \u00e9t\u00e9 lanc\u00e9es en combinant ProxyLogon, ProxyShell et Squirrelwaffle.<\/p>\n\n\n\n<p>L&rsquo;annonce indique que les serveurs sont exploit\u00e9s \u00e0 des fins de fraude financi\u00e8re. L&rsquo;exploitation a \u00e9t\u00e9 effectu\u00e9e sur des syst\u00e8mes vuln\u00e9rables qui n&rsquo;ont pas appliqu\u00e9 de mesures de s\u00e9curit\u00e9 strictes.<\/p>\n\n\n\n<p><strong>Exploit sur Microsoft Exchange Server<\/strong><\/p>\n\n\n\n<p>L&rsquo;une des fa\u00e7ons dont les utilisateurs peuvent se prot\u00e9ger de cette vuln\u00e9rabilit\u00e9 est d&rsquo;utiliser des <strong><a href=\"https:\/\/blog.koddos.net\/business-systems-face-a-myriad-of-attacks-as-hackers-guess-passwords\/\">mots de passe forts<\/a> <\/strong>qui s\u00e9curiseront les comptes en ligne contenant des informations pr\u00e9cieuses. L&rsquo;une des fa\u00e7ons de renforcer cette s\u00e9curit\u00e9 est d&rsquo;utiliser un processus d&rsquo;authentification \u00e0 deux facteurs qui renforce la s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>Un <strong><a href=\"https:\/\/news.sophos.com\/en-us\/2022\/02\/15\/vulnerable-exchange-server-hit-by-squirrelwaffle-and-financial-fraud\/\">rapport r\u00e9cent<\/a><\/strong> de Sophos a r\u00e9v\u00e9l\u00e9 l&rsquo;exploitation de Microsoft Exchange Server. La recherche indique que les vuln\u00e9rabilit\u00e9s du serveur n&rsquo;ont pas \u00e9t\u00e9 corrig\u00e9es, ce qui n&rsquo;a pas permis d&rsquo;assurer la protection n\u00e9cessaire contre les bugs qui pourraient \u00eatre d\u00e9tect\u00e9s et exploit\u00e9s par des acteurs de la menace. Les attaquants ont cibl\u00e9 ces vuln\u00e9rabilit\u00e9s pour acc\u00e9der aux fils de messagerie et envoyer des malspams.<\/p>\n\n\n\n<p>Microsoft a publi\u00e9 un correctif d&rsquo;urgence pour ces vuln\u00e9rabilit\u00e9s le 2 mars 2021. L&rsquo;entreprise a publi\u00e9 ces correctifs pour \u00e9liminer les vuln\u00e9rabilit\u00e9s zero-day qui pourraient \u00eatre utilis\u00e9es pour obtenir un acc\u00e8s non autoris\u00e9 aux serveurs. L&rsquo;un des groupes de hackers qui exploite les bugs est le groupe de menaces persistantes avanc\u00e9es (APT) Hafnium. Le groupe a exploit\u00e9 les vuln\u00e9rabilit\u00e9s avant la publication du correctif, et cette action a incit\u00e9 de nombreux autres APT \u00e0 exploiter \u00e9galement le bug.<\/p>\n\n\n\n<p>Comme dans de nombreux cas, certaines organisations n&rsquo;ont pas encore corrig\u00e9 les vuln\u00e9rabilit\u00e9s. L&rsquo;un des bugs les plus connus est la vuln\u00e9rabilit\u00e9 ProxyLogon\/ProxyShell, pour laquelle, malgr\u00e9 la publication d&rsquo;un correctif, certaines organisations ont laiss\u00e9 les serveurs sans correctif et ouverts aux attaques.<\/p>\n\n\n\n<p>Le r\u00e9cent rapport de Sophos a \u00e9tabli un lien entre l&rsquo;exploitation des vuln\u00e9rabilit\u00e9s de Microsoft Exchange Server et Squirrelwaffle. Squirrelwaffle est un chargeur de logiciels malveillants dont l&rsquo;activit\u00e9 a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e l&rsquo;ann\u00e9e derni\u00e8re apr\u00e8s avoir \u00e9t\u00e9 utilis\u00e9e dans une s\u00e9rie de campagnes malveillantes. Le chargeur de logiciels malveillants est g\u00e9n\u00e9ralement d\u00e9ploy\u00e9 sur les appareils de la victime par le biais de documents Microsoft Office ou DocuSign infect\u00e9s. Ces documents sont g\u00e9n\u00e9ralement joints sous la forme d&rsquo;un <strong><a href=\"https:\/\/blog.koddos.net\/colonial-pipeline-news-used-by-hackers-to-unleash-phishing-attacks\/\">e-mail de phishing<\/a><\/strong> incitant les utilisateurs peu m\u00e9fiants \u00e0 t\u00e9l\u00e9charger le logiciel malveillant sur leurs appareils.<\/p>\n\n\n\n<p>Lorsqu&rsquo;une victime active les macros dans les documents qui ont \u00e9t\u00e9 compromis, le chargeur de logiciels malveillants est utilis\u00e9 pour extraire et ex\u00e9cuter les balises CobaltStrike \u00e0 l&rsquo;aide d&rsquo;un script VBS. Le rapport de Sophos ajoute que le chargeur de logiciels malveillants a \u00e9t\u00e9 d\u00e9ploy\u00e9 sur les appareils apr\u00e8s que Microsoft Exchange Server ait \u00e9t\u00e9 affect\u00e9 lors de la derni\u00e8re campagne malveillante.<\/p>\n\n\n\n<p>Le rapport ajoute que le serveur utilis\u00e9 pour \u00ab\u00a0distribuer en masse\u00a0\u00bb le chargeur de logiciels malveillants appartenait \u00e0 une organisation non identifi\u00e9e. Le chargeur de logiciels malveillants Squirrelwaffle serait distribu\u00e9 \u00e0 des adresses \u00e9lectroniques internes et externes en obtenant un acc\u00e8s non autoris\u00e9 aux menaces existantes envoy\u00e9es par courriel entre les employ\u00e9s.<\/p>\n\n\n\n<p><strong>Les attaquants acc\u00e8dent aux donn\u00e9es de l&rsquo;organisation<\/strong><\/p>\n\n\n\n<p>Le d\u00e9tournement d&rsquo;un e-mail peut se faire de plusieurs mani\u00e8res. L&rsquo;un de ces moyens consiste en des fils de communication qui seront exploit\u00e9s \u00e0 l&rsquo;aide de l&rsquo;ing\u00e9nierie sociale et de l&rsquo;usurpation d&rsquo;identit\u00e9, l&rsquo;acteur malveillant se faisant passer pour un dirigeant de l&rsquo;entreprise et trompant le service comptable pour qu&rsquo;il approuve une fausse transaction. Les attaquants peuvent \u00e9galement envoyer un courriel contenant des liens dirigeant les employ\u00e9s vers des charges utiles de logiciels malveillants.<\/p>\n\n\n\n<p>Les attaquants ont utilis\u00e9 Squirrelwaffle pour diffuser le logiciel malveillant. Ils ont \u00e9galement franchi une \u00e9tape suppl\u00e9mentaire en acc\u00e9dant \u00e0 un fil de messagerie, puis en utilisant les informations internes pour r\u00e9aliser une fraude financi\u00e8re.<\/p>\n\n\n\n<p>Lorsque les attaquants ont eu acc\u00e8s aux serveurs de l&rsquo;organisation, ils ont recueilli des informations sur les clients. Les attaquants ont ensuite enregistr\u00e9 un domaine dont le nom \u00e9tait presque similaire \u00e0 celui de l&rsquo;organisation concern\u00e9e. Ils ont \u00e9galement cr\u00e9\u00e9 des comptes de messagerie en utilisant ce domaine et ont ensuite r\u00e9pondu aux clients en dehors de ses serveurs.<\/p>\n\n\n\n<p>Sophos a \u00e9galement d\u00e9clar\u00e9 que la l\u00e9gitimit\u00e9 des conversations \u00e9tait renforc\u00e9e lorsque l&rsquo;attaquant copiait diff\u00e9rentes adresses \u00e9lectroniques pour montrer qu&rsquo;il collaborait avec d&rsquo;autres d\u00e9partements. Cependant, l&rsquo;attaquant a cr\u00e9\u00e9 ces adresses e-mail suppl\u00e9mentaires pour que le mail ait l&rsquo;air authentique.<\/p>\n\n\n\n<p>Dans l&rsquo;un des cas, l&rsquo;attaquant a tent\u00e9 d&rsquo;initier une transaction financi\u00e8re. Cependant, la banque traitant la transaction n&rsquo;a pas donn\u00e9 suite apr\u00e8s avoir soup\u00e7onn\u00e9 que le destinataire pouvait \u00eatre frauduleux, et la victime n&rsquo;a pas subi de perte financi\u00e8re.<\/p>\n\n\n\n<p>Selon Matthew Everts, chercheur chez Sophos, la d\u00e9tection de ce logiciel malveillant montre que la correction des vuln\u00e9rabilit\u00e9s ne suffit pas.<\/p>\n\n\n\n<p>\u00ab\u00a0Dans le cas de serveurs Exchange vuln\u00e9rables, par exemple, il faut aussi v\u00e9rifier que les attaquants n&rsquo;ont pas laiss\u00e9 derri\u00e8re eux un shell web pour maintenir l&rsquo;acc\u00e8s. Et lorsqu&rsquo;il s&rsquo;agit d&rsquo;attaques d&rsquo;ing\u00e9nierie sociale sophistiqu\u00e9es, telles que celles utilis\u00e9es pour le d\u00e9tournement de fils de discussion, il est essentiel d&rsquo;informer les employ\u00e9s sur les points \u00e0 surveiller et sur la mani\u00e8re de les signaler pour les d\u00e9tecter\u00a0\u00bb, ajoute M. Everts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une s\u00e9rie d&rsquo;attaques de cybers\u00e9curit\u00e9 a \u00e9t\u00e9 d\u00e9tect\u00e9e sur Microsoft Exchange Server. Les attaques ont \u00e9t\u00e9 lanc\u00e9es en combinant ProxyLogon, ProxyShell et Squirrelwaffle. L&rsquo;annonce indique que les serveurs sont exploit\u00e9s \u00e0 des fins de fraude financi\u00e8re. L&rsquo;exploitation a \u00e9t\u00e9 effectu\u00e9e sur des syst\u00e8mes vuln\u00e9rables qui n&rsquo;ont pas appliqu\u00e9 de mesures de s\u00e9curit\u00e9 strictes. Exploit sur &hellip; <a href=\"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":3337,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-3956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS\" \/>\n<meta property=\"og:description\" content=\"Une s\u00e9rie d&rsquo;attaques de cybers\u00e9curit\u00e9 a \u00e9t\u00e9 d\u00e9tect\u00e9e sur Microsoft Exchange Server. Les attaques ont \u00e9t\u00e9 lanc\u00e9es en combinant ProxyLogon, ProxyShell et Squirrelwaffle. L&rsquo;annonce indique que les serveurs sont exploit\u00e9s \u00e0 des fins de fraude financi\u00e8re. L&rsquo;exploitation a \u00e9t\u00e9 effectu\u00e9e sur des syst\u00e8mes vuln\u00e9rables qui n&rsquo;ont pas appliqu\u00e9 de mesures de s\u00e9curit\u00e9 strictes. Exploit sur &hellip; Continue reading UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog KoDDoS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/koddosCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T08:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-16T18:25:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"KoDDoS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@koddoscom\" \/>\n<meta name=\"twitter:site\" content=\"@koddoscom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"KoDDoS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/\"},\"author\":{\"name\":\"KoDDoS\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/person\\\/d22f7fb31dc4d117c9eb5c9cfe533f85\"},\"headline\":\"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER\",\"datePublished\":\"2022-02-16T08:19:00+00:00\",\"dateModified\":\"2022-02-16T18:25:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/\"},\"wordCount\":1008,\"publisher\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/\",\"name\":\"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1\",\"datePublished\":\"2022-02-16T08:19:00+00:00\",\"dateModified\":\"2022-02-16T18:25:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\",\"name\":\"Blog KoDDoS\",\"description\":\"Blog KoDDoS est un blog d\u2019information et d\u2019actualit\u00e9 focalis\u00e9 sur le hacking, la cyber criminalit\u00e9, la vie priv\u00e9e et la surveillance.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#organization\",\"name\":\"KoDDoS\",\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo.png?fit=258%2C55&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/fr.koddos.net\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo.png?fit=258%2C55&ssl=1\",\"width\":258,\"height\":55,\"caption\":\"KoDDoS\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/koddosCom\",\"https:\\\/\\\/x.com\\\/koddoscom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/#\\\/schema\\\/person\\\/d22f7fb31dc4d117c9eb5c9cfe533f85\",\"name\":\"KoDDoS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g\",\"caption\":\"KoDDoS\"},\"url\":\"https:\\\/\\\/fr.koddos.net\\\/blog\\\/author\\\/oiyndjepop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/","og_locale":"fr_FR","og_type":"article","og_title":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS","og_description":"Une s\u00e9rie d&rsquo;attaques de cybers\u00e9curit\u00e9 a \u00e9t\u00e9 d\u00e9tect\u00e9e sur Microsoft Exchange Server. Les attaques ont \u00e9t\u00e9 lanc\u00e9es en combinant ProxyLogon, ProxyShell et Squirrelwaffle. L&rsquo;annonce indique que les serveurs sont exploit\u00e9s \u00e0 des fins de fraude financi\u00e8re. L&rsquo;exploitation a \u00e9t\u00e9 effectu\u00e9e sur des syst\u00e8mes vuln\u00e9rables qui n&rsquo;ont pas appliqu\u00e9 de mesures de s\u00e9curit\u00e9 strictes. Exploit sur &hellip; Continue reading UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER","og_url":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/","og_site_name":"Blog KoDDoS","article_publisher":"https:\/\/www.facebook.com\/koddosCom","article_published_time":"2022-02-16T08:19:00+00:00","article_modified_time":"2022-02-16T18:25:51+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg","type":"image\/jpeg"}],"author":"KoDDoS","twitter_card":"summary_large_image","twitter_creator":"@koddoscom","twitter_site":"@koddoscom","twitter_misc":{"\u00c9crit par":"KoDDoS","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#article","isPartOf":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/"},"author":{"name":"KoDDoS","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/person\/d22f7fb31dc4d117c9eb5c9cfe533f85"},"headline":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER","datePublished":"2022-02-16T08:19:00+00:00","dateModified":"2022-02-16T18:25:51+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/"},"wordCount":1008,"publisher":{"@id":"https:\/\/fr.koddos.net\/blog\/#organization"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/","url":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/","name":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER - Blog KoDDoS","isPartOf":{"@id":"https:\/\/fr.koddos.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#primaryimage"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1","datePublished":"2022-02-16T08:19:00+00:00","dateModified":"2022-02-16T18:25:51+00:00","breadcrumb":{"@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#primaryimage","url":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/fr.koddos.net\/blog\/une-etude-de-sophos-revele-des-vulnerabilites-exploitees-sur-microsoft-exchange-server\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.koddos.net\/blog\/"},{"@type":"ListItem","position":2,"name":"UNE \u00c9TUDE DE SOPHOS R\u00c9V\u00c8LE DES VULN\u00c9RABILIT\u00c9S EXPLOIT\u00c9ES SUR MICROSOFT EXCHANGE SERVER"}]},{"@type":"WebSite","@id":"https:\/\/fr.koddos.net\/blog\/#website","url":"https:\/\/fr.koddos.net\/blog\/","name":"Blog KoDDoS","description":"Blog KoDDoS est un blog d\u2019information et d\u2019actualit\u00e9 focalis\u00e9 sur le hacking, la cyber criminalit\u00e9, la vie priv\u00e9e et la surveillance.","publisher":{"@id":"https:\/\/fr.koddos.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.koddos.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fr.koddos.net\/blog\/#organization","name":"KoDDoS","url":"https:\/\/fr.koddos.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2018\/02\/logo.png?fit=258%2C55&ssl=1","contentUrl":"https:\/\/i1.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2018\/02\/logo.png?fit=258%2C55&ssl=1","width":258,"height":55,"caption":"KoDDoS"},"image":{"@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/koddosCom","https:\/\/x.com\/koddoscom"]},{"@type":"Person","@id":"https:\/\/fr.koddos.net\/blog\/#\/schema\/person\/d22f7fb31dc4d117c9eb5c9cfe533f85","name":"KoDDoS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/239872ddb935e40a5bf46e7421e0fdd8419ae8e91164a61d84219911f7648c73?s=96&d=mm&r=g","caption":"KoDDoS"},"url":"https:\/\/fr.koddos.net\/blog\/author\/oiyndjepop\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9DjzA-11O","jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fr.koddos.net\/blog\/wp-content\/uploads\/2021\/06\/Hackers-Are-Using-BazaCall-To-Launch-Malware-Campaign-In-Microsoft-Office.jpg?fit=640%2C426&ssl=1","_links":{"self":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/comments?post=3956"}],"version-history":[{"count":1,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3956\/revisions"}],"predecessor-version":[{"id":3957,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/posts\/3956\/revisions\/3957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/media\/3337"}],"wp:attachment":[{"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/media?parent=3956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/categories?post=3956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.koddos.net\/blog\/wp-json\/wp\/v2\/tags?post=3956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}